{"id":177956,"date":"2026-05-09T02:34:10","date_gmt":"2026-05-09T00:34:10","guid":{"rendered":"https:\/\/tupique.com\/product\/montre-homme-police-pewgk0093103\/"},"modified":"2026-05-11T21:22:38","modified_gmt":"2026-05-11T19:22:38","slug":"montre-homme-police-pewgk0093103","status":"publish","type":"product","link":"https:\/\/tupique.com\/en\/product\/montre-homme-police-pewgk0093103\/","title":{"rendered":"Police Men's Watch PEWGK0093103"},"content":{"rendered":"<p>Si vous aimez suivre les derni\u00e8res tendances en mati\u00e8re de mode et accessoires, achetez <b>Police Men's Watch PEWGK0093103<\/b> au meilleur prix.<\/p>\n<ul>\n<li>Genre: Homme<\/li>\n<li>Liens suppl\u00e9mentaires: Non<\/li>\n<li>Type de montre: Montre-bracelet<\/li>\n<li>Style: Bracelet<\/li>\n<li>Mat\u00e9riau du bracelet: Silicone<\/li>\n<li>Forme: Rond<\/li>\n<li>Taille: 43 mm<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p><span class=\"unit-info\">6534.6512 &euro; \/ 1 m<\/span><\/p>","protected":false},"featured_media":177950,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[823],"product_cat":[544,574,545],"product_tag":[103,543],"woo-feed-brand":[],"class_list":{"0":"post-177956","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-brandp_867","7":"product_cat-mode-accessoires","8":"product_cat-montres-homme","9":"product_cat-montres-bracelets","10":"product_tag-tag_1261","11":"product_tag-tag_61","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Montre Homme Police PEWGK0093103 | | Tupique<\/title>\n<meta name=\"description\" content=\"Envie d&#039;acheter Montre Homme Police PEWGK0093103\u00a0? Achetez Montre Homme Police PEWGK0093103 maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tupique.com\/en\/product\/montre-homme-police-pewgk0093103\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Montre Homme Police PEWGK0093103 | | Tupique\" \/>\n<meta property=\"og:description\" content=\"Envie d&#039;acheter Montre Homme Police PEWGK0093103\u00a0? Achetez Montre Homme Police PEWGK0093103 maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tupique.com\/en\/product\/montre-homme-police-pewgk0093103\/\" \/>\n<meta property=\"og:site_name\" content=\"Tupique\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T19:22:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tupique.com\/wp-content\/uploads\/2026\/05\/4894816187040_S72136918_P00.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tupique.com\\\/product\\\/montre-homme-police-pewgk0093103\\\/\",\"url\":\"https:\\\/\\\/tupique.com\\\/product\\\/montre-homme-police-pewgk0093103\\\/\",\"name\":\"Montre Homme Police PEWGK0093103 | | Tupique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/product\\\/montre-homme-police-pewgk0093103\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/product\\\/montre-homme-police-pewgk0093103\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/4894816187040_S72136918_P00.jpg\",\"datePublished\":\"2026-05-09T00:34:10+00:00\",\"dateModified\":\"2026-05-11T19:22:38+00:00\",\"description\":\"Envie d'acheter Montre Homme Police PEWGK0093103\u00a0? Achetez Montre Homme Police PEWGK0093103 maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/product\\\/montre-homme-police-pewgk0093103\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tupique.com\\\/product\\\/montre-homme-police-pewgk0093103\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/tupique.com\\\/product\\\/montre-homme-police-pewgk0093103\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/4894816187040_S72136918_P00.jpg\",\"contentUrl\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/4894816187040_S72136918_P00.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"S72136918_0\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tupique.com\\\/product\\\/montre-homme-police-pewgk0093103\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"commencer\",\"item\":\"https:\\\/\\\/tupique.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/tupique.com\\\/pt\\\/loja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Montre Homme Police PEWGK0093103\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tupique.com\\\/#website\",\"url\":\"https:\\\/\\\/tupique.com\\\/\",\"name\":\"Tupique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tupique.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tupique.com\\\/#organization\",\"name\":\"Tupique\",\"url\":\"https:\\\/\\\/tupique.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/tupique.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-tupique-1.webp\",\"contentUrl\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-tupique-1.webp\",\"width\":500,\"height\":67,\"caption\":\"Tupique\"},\"image\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Montre Homme Police PEWGK0093103 | | Tupique","description":"Envie d'acheter Montre Homme Police PEWGK0093103\u00a0? Achetez Montre Homme Police PEWGK0093103 maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tupique.com\/en\/product\/montre-homme-police-pewgk0093103\/","og_locale":"en_GB","og_type":"article","og_title":"Montre Homme Police PEWGK0093103 | | Tupique","og_description":"Envie d'acheter Montre Homme Police PEWGK0093103\u00a0? Achetez Montre Homme Police PEWGK0093103 maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.","og_url":"https:\/\/tupique.com\/en\/product\/montre-homme-police-pewgk0093103\/","og_site_name":"Tupique","article_modified_time":"2026-05-11T19:22:38+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/05\/4894816187040_S72136918_P00.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tupique.com\/product\/montre-homme-police-pewgk0093103\/","url":"https:\/\/tupique.com\/product\/montre-homme-police-pewgk0093103\/","name":"Montre Homme Police PEWGK0093103 | | Tupique","isPartOf":{"@id":"https:\/\/tupique.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tupique.com\/product\/montre-homme-police-pewgk0093103\/#primaryimage"},"image":{"@id":"https:\/\/tupique.com\/product\/montre-homme-police-pewgk0093103\/#primaryimage"},"thumbnailUrl":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/05\/4894816187040_S72136918_P00.jpg","datePublished":"2026-05-09T00:34:10+00:00","dateModified":"2026-05-11T19:22:38+00:00","description":"Envie d'acheter Montre Homme Police PEWGK0093103\u00a0? Achetez Montre Homme Police PEWGK0093103 maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.","breadcrumb":{"@id":"https:\/\/tupique.com\/product\/montre-homme-police-pewgk0093103\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tupique.com\/product\/montre-homme-police-pewgk0093103\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/tupique.com\/product\/montre-homme-police-pewgk0093103\/#primaryimage","url":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/05\/4894816187040_S72136918_P00.jpg","contentUrl":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/05\/4894816187040_S72136918_P00.jpg","width":1200,"height":1200,"caption":"S72136918_0"},{"@type":"BreadcrumbList","@id":"https:\/\/tupique.com\/product\/montre-homme-police-pewgk0093103\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"commencer","item":"https:\/\/tupique.com\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/tupique.com\/pt\/loja\/"},{"@type":"ListItem","position":3,"name":"Montre Homme Police PEWGK0093103"}]},{"@type":"WebSite","@id":"https:\/\/tupique.com\/#website","url":"https:\/\/tupique.com\/","name":"Tupique","description":"","publisher":{"@id":"https:\/\/tupique.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tupique.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/tupique.com\/#organization","name":"Tupique","url":"https:\/\/tupique.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/tupique.com\/#\/schema\/logo\/image\/","url":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/03\/logo-tupique-1.webp","contentUrl":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/03\/logo-tupique-1.webp","width":500,"height":67,"caption":"Tupique"},"image":{"@id":"https:\/\/tupique.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/tupique.com\/en\/wp-json\/wp\/v2\/product\/177956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tupique.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tupique.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/tupique.com\/en\/wp-json\/wp\/v2\/comments?post=177956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tupique.com\/en\/wp-json\/wp\/v2\/media\/177950"}],"wp:attachment":[{"href":"https:\/\/tupique.com\/en\/wp-json\/wp\/v2\/media?parent=177956"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/tupique.com\/en\/wp-json\/wp\/v2\/product_brand?post=177956"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tupique.com\/en\/wp-json\/wp\/v2\/product_cat?post=177956"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tupique.com\/en\/wp-json\/wp\/v2\/product_tag?post=177956"},{"taxonomy":"woo-feed-brand","embeddable":true,"href":"https:\/\/tupique.com\/en\/wp-json\/wp\/v2\/woo-feed-brand?post=177956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}