{"id":193598,"date":"2026-05-12T03:40:24","date_gmt":"2026-05-12T01:40:24","guid":{"rendered":"https:\/\/tupique.com\/product\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\/"},"modified":"2026-05-12T03:40:24","modified_gmt":"2026-05-12T01:40:24","slug":"horloge-murale-ingersoll-1892-ic003gb-dore-noir","status":"publish","type":"product","link":"https:\/\/tupique.com\/en\/product\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\/","title":{"rendered":"Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir"},"content":{"rendered":"<p>Si vous aimez prendre soin de chaque d\u00e9tail de votre maison et d&#8217;\u00eatre \u00e0 la derni\u00e8re mode en mati\u00e8re de produits qui vous rendront la vie plus facile, achetez <b>Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir<\/b> au meilleur prix.<\/p>\n<ul>\n<li>Type: Horloge Murale<\/li>\n<li>Couleur du cadran: Noir<\/li>\n<li>Forme: Rond<\/li>\n<li>Bloc d\u2019Alimentation: Batterie<\/li>\n<li>Couleur: Dor\u00e9<\/li>\n<li>Type d&#8217;installation: Montage mural<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Si vous aimez prendre soin de chaque d\u00e9tail de votre maison et d&#8217;\u00eatre \u00e0 la derni\u00e8re mode en mati\u00e8re de produits qui vous rendront la vie plus facile, achetez Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir au meilleur prix. Type: Horloge Murale Couleur du cadran: Noir Forme: Rond Bloc d\u2019Alimentation: Batterie Couleur: Dor\u00e9 Type d&#8217;installation: [&hellip;]<\/p>\n","protected":false},"featured_media":193594,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[835],"product_cat":[1430,1731,239],"product_tag":[],"woo-feed-brand":[],"class_list":{"0":"post-193598","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-brandp_7989","7":"product_cat-decoration-et-eclairage","8":"product_cat-horloges-murales-et-de-table","9":"product_cat-maison-jardin","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir | | Tupique<\/title>\n<meta name=\"description\" content=\"Envie d&#039;acheter Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir\u00a0? Achetez Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tupique.com\/en\/product\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir | | Tupique\" \/>\n<meta property=\"og:description\" content=\"Envie d&#039;acheter Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir\u00a0? Achetez Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tupique.com\/en\/product\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\/\" \/>\n<meta property=\"og:site_name\" content=\"Tupique\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tupique.com\/wp-content\/uploads\/2026\/05\/5013348514943_R00.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tupique.com\\\/product\\\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\\\/\",\"url\":\"https:\\\/\\\/tupique.com\\\/product\\\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\\\/\",\"name\":\"Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir | | Tupique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/product\\\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/product\\\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/5013348514943_R00.jpg\",\"datePublished\":\"2026-05-12T01:40:24+00:00\",\"description\":\"Envie d'acheter Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir\u00a0? Achetez Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/product\\\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tupique.com\\\/product\\\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/tupique.com\\\/product\\\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/5013348514943_R00.jpg\",\"contentUrl\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/5013348514943_R00.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"S7295337_0\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tupique.com\\\/product\\\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"commencer\",\"item\":\"https:\\\/\\\/tupique.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/tupique.com\\\/pt\\\/loja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tupique.com\\\/#website\",\"url\":\"https:\\\/\\\/tupique.com\\\/\",\"name\":\"Tupique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tupique.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tupique.com\\\/#organization\",\"name\":\"Tupique\",\"url\":\"https:\\\/\\\/tupique.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/tupique.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-tupique-1.webp\",\"contentUrl\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-tupique-1.webp\",\"width\":500,\"height\":67,\"caption\":\"Tupique\"},\"image\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir | | Tupique","description":"Envie d'acheter Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir\u00a0? Achetez Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tupique.com\/en\/product\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\/","og_locale":"en_GB","og_type":"article","og_title":"Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir | | Tupique","og_description":"Envie d'acheter Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir\u00a0? Achetez Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.","og_url":"https:\/\/tupique.com\/en\/product\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\/","og_site_name":"Tupique","og_image":[{"width":1200,"height":1200,"url":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/05\/5013348514943_R00.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tupique.com\/product\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\/","url":"https:\/\/tupique.com\/product\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\/","name":"Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir | | Tupique","isPartOf":{"@id":"https:\/\/tupique.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tupique.com\/product\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\/#primaryimage"},"image":{"@id":"https:\/\/tupique.com\/product\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\/#primaryimage"},"thumbnailUrl":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/05\/5013348514943_R00.jpg","datePublished":"2026-05-12T01:40:24+00:00","description":"Envie d'acheter Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir\u00a0? Achetez Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.","breadcrumb":{"@id":"https:\/\/tupique.com\/product\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tupique.com\/product\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/tupique.com\/product\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\/#primaryimage","url":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/05\/5013348514943_R00.jpg","contentUrl":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/05\/5013348514943_R00.jpg","width":1200,"height":1200,"caption":"S7295337_0"},{"@type":"BreadcrumbList","@id":"https:\/\/tupique.com\/product\/horloge-murale-ingersoll-1892-ic003gb-dore-noir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"commencer","item":"https:\/\/tupique.com\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/tupique.com\/pt\/loja\/"},{"@type":"ListItem","position":3,"name":"Horloge Murale Ingersoll 1892 IC003GB Dor\u00e9 Noir"}]},{"@type":"WebSite","@id":"https:\/\/tupique.com\/#website","url":"https:\/\/tupique.com\/","name":"Tupique","description":"","publisher":{"@id":"https:\/\/tupique.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tupique.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/tupique.com\/#organization","name":"Tupique","url":"https:\/\/tupique.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/tupique.com\/#\/schema\/logo\/image\/","url":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/03\/logo-tupique-1.webp","contentUrl":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/03\/logo-tupique-1.webp","width":500,"height":67,"caption":"Tupique"},"image":{"@id":"https:\/\/tupique.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/tupique.com\/en\/wp-json\/wp\/v2\/product\/193598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tupique.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tupique.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/tupique.com\/en\/wp-json\/wp\/v2\/comments?post=193598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tupique.com\/en\/wp-json\/wp\/v2\/media\/193594"}],"wp:attachment":[{"href":"https:\/\/tupique.com\/en\/wp-json\/wp\/v2\/media?parent=193598"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/tupique.com\/en\/wp-json\/wp\/v2\/product_brand?post=193598"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tupique.com\/en\/wp-json\/wp\/v2\/product_cat?post=193598"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tupique.com\/en\/wp-json\/wp\/v2\/product_tag?post=193598"},{"taxonomy":"woo-feed-brand","embeddable":true,"href":"https:\/\/tupique.com\/en\/wp-json\/wp\/v2\/woo-feed-brand?post=193598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}