{"id":183811,"date":"2026-05-11T17:28:18","date_gmt":"2026-05-11T15:28:18","guid":{"rendered":"https:\/\/tupique.com\/product\/etoile-de-noel-krist-rouge-acier-plastique\/"},"modified":"2026-05-11T21:18:38","modified_gmt":"2026-05-11T19:18:38","slug":"etoile-de-noel-krist-rouge-acier-plastique","status":"publish","type":"product","link":"https:\/\/tupique.com\/pt\/product\/etoile-de-noel-krist-rouge-acier-plastique\/","title":{"rendered":"Estrela de Natal Krist+ Vermelho A\u00e7o Pl\u00e1stico"},"content":{"rendered":"<p>Vous voulez donner une touche d&#8217;originalit\u00e9 \u00e0 votre maison ? Vous y arriverez gr\u00e2ce au <b>Estrela de Natal Krist+ Vermelho A\u00e7o Pl\u00e1stico<\/b>.<\/p>\n<ul>\n<li>Tipo:\n<ul>\n<li>D\u00e9corations de No\u00ebl<\/li>\n<li>D\u00e9coration Suspendue<\/li>\n<\/ul>\n<\/li>\n<li>Design: \u00c9toile<\/li>\n<li>Couleur: Rouge<\/li>\n<li>Mat\u00e9riel:\n<ul>\n<li>Acier<\/li>\n<li>Plastique<\/li>\n<\/ul>\n<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Vous voulez donner une touche d&#8217;originalit\u00e9 \u00e0 votre maison ? Vous y arriverez gr\u00e2ce au \u00c9toile de No\u00ebl Krist+ Rouge Acier Plastique. Type: D\u00e9corations de No\u00ebl D\u00e9coration Suspendue Design: \u00c9toile Couleur: Rouge Mat\u00e9riel: Acier Plastique<\/p>","protected":false},"featured_media":183810,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[2416],"product_cat":[1703,1430,239],"product_tag":[101,215],"woo-feed-brand":[],"class_list":{"0":"post-183811","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-brandp_6833","7":"product_cat-decoration-de-noel","8":"product_cat-decoration-et-eclairage","9":"product_cat-maison-jardin","10":"product_tag-tag_599","11":"product_tag-tag_427","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9toile de No\u00ebl Krist+ Rouge Acier Plastique | | Tupique<\/title>\n<meta name=\"description\" content=\"Envie d&#039;acheter \u00c9toile de No\u00ebl Krist+ Rouge Acier Plastique\u00a0? Achetez \u00c9toile de No\u00ebl Krist+ Rouge Acier Plastique maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tupique.com\/pt\/product\/etoile-de-noel-krist-rouge-acier-plastique\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9toile de No\u00ebl Krist+ Rouge Acier Plastique | | Tupique\" \/>\n<meta property=\"og:description\" content=\"Envie d&#039;acheter \u00c9toile de No\u00ebl Krist+ Rouge Acier Plastique\u00a0? Achetez \u00c9toile de No\u00ebl Krist+ Rouge Acier Plastique maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tupique.com\/pt\/product\/etoile-de-noel-krist-rouge-acier-plastique\/\" \/>\n<meta property=\"og:site_name\" content=\"Tupique\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T19:18:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tupique.com\/wp-content\/uploads\/2026\/05\/8430852906465_S3612167_P0-v_12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tupique.com\\\/product\\\/etoile-de-noel-krist-rouge-acier-plastique\\\/\",\"url\":\"https:\\\/\\\/tupique.com\\\/product\\\/etoile-de-noel-krist-rouge-acier-plastique\\\/\",\"name\":\"\u00c9toile de No\u00ebl Krist+ Rouge Acier Plastique | | Tupique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/product\\\/etoile-de-noel-krist-rouge-acier-plastique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/product\\\/etoile-de-noel-krist-rouge-acier-plastique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/8430852906465_S3612167_P0-v_12.jpg\",\"datePublished\":\"2026-05-11T15:28:18+00:00\",\"dateModified\":\"2026-05-11T19:18:38+00:00\",\"description\":\"Envie d'acheter \u00c9toile de No\u00ebl Krist+ Rouge Acier Plastique\u00a0? Achetez \u00c9toile de No\u00ebl Krist+ Rouge Acier Plastique maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/product\\\/etoile-de-noel-krist-rouge-acier-plastique\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tupique.com\\\/product\\\/etoile-de-noel-krist-rouge-acier-plastique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/tupique.com\\\/product\\\/etoile-de-noel-krist-rouge-acier-plastique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/8430852906465_S3612167_P0-v_12.jpg\",\"contentUrl\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/8430852906465_S3612167_P0-v_12.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"S3612167_0\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tupique.com\\\/product\\\/etoile-de-noel-krist-rouge-acier-plastique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"commencer\",\"item\":\"https:\\\/\\\/tupique.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/tupique.com\\\/pt\\\/loja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c9toile de No\u00ebl Krist+ Rouge Acier Plastique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tupique.com\\\/#website\",\"url\":\"https:\\\/\\\/tupique.com\\\/\",\"name\":\"Tupique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tupique.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tupique.com\\\/#organization\",\"name\":\"Tupique\",\"url\":\"https:\\\/\\\/tupique.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/tupique.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-tupique-1.webp\",\"contentUrl\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-tupique-1.webp\",\"width\":500,\"height\":67,\"caption\":\"Tupique\"},\"image\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9toile de No\u00ebl Krist+ Rouge Acier Plastique | | Tupique","description":"Envie d'acheter \u00c9toile de No\u00ebl Krist+ Rouge Acier Plastique\u00a0? Achetez \u00c9toile de No\u00ebl Krist+ Rouge Acier Plastique maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tupique.com\/pt\/product\/etoile-de-noel-krist-rouge-acier-plastique\/","og_locale":"pt_PT","og_type":"article","og_title":"\u00c9toile de No\u00ebl Krist+ Rouge Acier Plastique | | Tupique","og_description":"Envie d'acheter \u00c9toile de No\u00ebl Krist+ Rouge Acier Plastique\u00a0? Achetez \u00c9toile de No\u00ebl Krist+ Rouge Acier Plastique maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.","og_url":"https:\/\/tupique.com\/pt\/product\/etoile-de-noel-krist-rouge-acier-plastique\/","og_site_name":"Tupique","article_modified_time":"2026-05-11T19:18:38+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/05\/8430852906465_S3612167_P0-v_12.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tupique.com\/product\/etoile-de-noel-krist-rouge-acier-plastique\/","url":"https:\/\/tupique.com\/product\/etoile-de-noel-krist-rouge-acier-plastique\/","name":"\u00c9toile de No\u00ebl Krist+ Rouge Acier Plastique | | Tupique","isPartOf":{"@id":"https:\/\/tupique.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tupique.com\/product\/etoile-de-noel-krist-rouge-acier-plastique\/#primaryimage"},"image":{"@id":"https:\/\/tupique.com\/product\/etoile-de-noel-krist-rouge-acier-plastique\/#primaryimage"},"thumbnailUrl":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/05\/8430852906465_S3612167_P0-v_12.jpg","datePublished":"2026-05-11T15:28:18+00:00","dateModified":"2026-05-11T19:18:38+00:00","description":"Envie d'acheter \u00c9toile de No\u00ebl Krist+ Rouge Acier Plastique\u00a0? Achetez \u00c9toile de No\u00ebl Krist+ Rouge Acier Plastique maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.","breadcrumb":{"@id":"https:\/\/tupique.com\/product\/etoile-de-noel-krist-rouge-acier-plastique\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tupique.com\/product\/etoile-de-noel-krist-rouge-acier-plastique\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/tupique.com\/product\/etoile-de-noel-krist-rouge-acier-plastique\/#primaryimage","url":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/05\/8430852906465_S3612167_P0-v_12.jpg","contentUrl":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/05\/8430852906465_S3612167_P0-v_12.jpg","width":1200,"height":1200,"caption":"S3612167_0"},{"@type":"BreadcrumbList","@id":"https:\/\/tupique.com\/product\/etoile-de-noel-krist-rouge-acier-plastique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"commencer","item":"https:\/\/tupique.com\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/tupique.com\/pt\/loja\/"},{"@type":"ListItem","position":3,"name":"\u00c9toile de No\u00ebl Krist+ Rouge Acier Plastique"}]},{"@type":"WebSite","@id":"https:\/\/tupique.com\/#website","url":"https:\/\/tupique.com\/","name":"Tupique","description":"","publisher":{"@id":"https:\/\/tupique.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tupique.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/tupique.com\/#organization","name":"Tupique","url":"https:\/\/tupique.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/tupique.com\/#\/schema\/logo\/image\/","url":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/03\/logo-tupique-1.webp","contentUrl":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/03\/logo-tupique-1.webp","width":500,"height":67,"caption":"Tupique"},"image":{"@id":"https:\/\/tupique.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/product\/183811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/comments?post=183811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/media\/183810"}],"wp:attachment":[{"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/media?parent=183811"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/product_brand?post=183811"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/product_cat?post=183811"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/product_tag?post=183811"},{"taxonomy":"woo-feed-brand","embeddable":true,"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/woo-feed-brand?post=183811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}