{"id":187646,"date":"2026-05-11T20:58:42","date_gmt":"2026-05-11T18:58:42","guid":{"rendered":"https:\/\/tupique.com\/product\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\/"},"modified":"2026-05-11T21:23:41","modified_gmt":"2026-05-11T19:23:41","slug":"voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent","status":"publish","type":"product","link":"https:\/\/tupique.com\/pt\/product\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\/","title":{"rendered":"Voile d&#8217;ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent"},"content":{"rendered":"<p>Si vous aimez prendre soin de chaque d\u00e9tail de votre maison et d&#8217;\u00eatre \u00e0 la derni\u00e8re mode en mati\u00e8re de produits qui vous rendront la vie plus facile, achetez <b>Voile d&#8217;ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent<\/b> au meilleur prix.<\/p>\n<ul>\n<li>Caracter\u00edsticas:\n<ul>\n<li>Renforc\u00e9e<\/li>\n<li>R\u00e9sistant aux UV<\/li>\n<li>Renforc\u00e9<\/li>\n<\/ul>\n<\/li>\n<li>Inclut:\n<ul>\n<li>Corde<\/li>\n<li>Cordes<\/li>\n<li>Fixations<\/li>\n<\/ul>\n<\/li>\n<li>Tipo:\n<ul>\n<li>Auvent<\/li>\n<li>Voile d&#8217;ombrage<\/li>\n<\/ul>\n<\/li>\n<li>N\u00e9cessite un montage: Non<\/li>\n<li>Long: 500 cm<\/li>\n<li>Design: Triangulaire<\/li>\n<li>Largeur: 500 cm<\/li>\n<li>Mati\u00e8re: Poly\u00e9thyl\u00e8ne<\/li>\n<li>Couleur: Vert<\/li>\n<li>taux d&#8217;occultation: 95 %<\/li>\n<li>Dimensions approx.: 500 x 500 x 0,5 cm<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Si vous aimez prendre soin de chaque d\u00e9tail de votre maison et d&#8217;\u00eatre \u00e0 la derni\u00e8re mode en mati\u00e8re de produits qui vous rendront la vie plus facile, achetez Voile d&#8217;ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent au meilleur prix. Caract\u00e9ristiques: Renforc\u00e9e R\u00e9sistant aux UV Renforc\u00e9 Inclut: Corde Cordes Fixations Type: [&hellip;]<\/p>\n","protected":false},"featured_media":187640,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[122],"product_cat":[759,239,974],"product_tag":[211],"woo-feed-brand":[],"class_list":{"0":"post-187646","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-brandp_2386","7":"product_cat-jardin-et-terrasse","8":"product_cat-maison-jardin","9":"product_cat-mobilier-d-exterieur","10":"product_tag-tag_3","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Voile d&#039;ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent | | Tupique<\/title>\n<meta name=\"description\" content=\"Envie d&#039;acheter Voile d&#039;ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent\u00a0? Achetez Voile d&#039;ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tupique.com\/pt\/product\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Voile d&#039;ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent | | Tupique\" \/>\n<meta property=\"og:description\" content=\"Envie d&#039;acheter Voile d&#039;ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent\u00a0? Achetez Voile d&#039;ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tupique.com\/pt\/product\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\/\" \/>\n<meta property=\"og:site_name\" content=\"Tupique\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T19:23:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tupique.com\/wp-content\/uploads\/2026\/05\/8424346271399_S8700130_P01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tupique.com\\\/pt\\\/product\\\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\\\/\",\"url\":\"https:\\\/\\\/tupique.com\\\/pt\\\/product\\\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\\\/\",\"name\":\"Voile d'ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent | | Tupique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/pt\\\/product\\\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/pt\\\/product\\\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/8424346271399_S8700130_P01.jpg\",\"datePublished\":\"2026-05-11T18:58:42+00:00\",\"dateModified\":\"2026-05-11T19:23:41+00:00\",\"description\":\"Envie d'acheter Voile d'ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent\u00a0? Achetez Voile d'ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/pt\\\/product\\\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tupique.com\\\/pt\\\/product\\\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/tupique.com\\\/pt\\\/product\\\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/8424346271399_S8700130_P01.jpg\",\"contentUrl\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/8424346271399_S8700130_P01.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"S8700130_0\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tupique.com\\\/pt\\\/product\\\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"commencer\",\"item\":\"https:\\\/\\\/tupique.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/tupique.com\\\/pt\\\/loja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Voile d&#8217;ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tupique.com\\\/#website\",\"url\":\"https:\\\/\\\/tupique.com\\\/\",\"name\":\"Tupique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tupique.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tupique.com\\\/#organization\",\"name\":\"Tupique\",\"url\":\"https:\\\/\\\/tupique.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/tupique.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-tupique-1.webp\",\"contentUrl\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-tupique-1.webp\",\"width\":500,\"height\":67,\"caption\":\"Tupique\"},\"image\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Voile d'ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent | | Tupique","description":"Envie d'acheter Voile d'ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent\u00a0? Achetez Voile d'ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tupique.com\/pt\/product\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\/","og_locale":"pt_PT","og_type":"article","og_title":"Voile d'ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent | | Tupique","og_description":"Envie d'acheter Voile d'ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent\u00a0? Achetez Voile d'ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.","og_url":"https:\/\/tupique.com\/pt\/product\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\/","og_site_name":"Tupique","article_modified_time":"2026-05-11T19:23:41+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/05\/8424346271399_S8700130_P01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tupique.com\/pt\/product\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\/","url":"https:\/\/tupique.com\/pt\/product\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\/","name":"Voile d'ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent | | Tupique","isPartOf":{"@id":"https:\/\/tupique.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tupique.com\/pt\/product\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\/#primaryimage"},"image":{"@id":"https:\/\/tupique.com\/pt\/product\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\/#primaryimage"},"thumbnailUrl":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/05\/8424346271399_S8700130_P01.jpg","datePublished":"2026-05-11T18:58:42+00:00","dateModified":"2026-05-11T19:23:41+00:00","description":"Envie d'acheter Voile d'ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent\u00a0? Achetez Voile d'ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent maintenant avec Tupique en 3 versements sans int\u00e9r\u00eat.","breadcrumb":{"@id":"https:\/\/tupique.com\/pt\/product\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tupique.com\/pt\/product\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/tupique.com\/pt\/product\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\/#primaryimage","url":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/05\/8424346271399_S8700130_P01.jpg","contentUrl":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/05\/8424346271399_S8700130_P01.jpg","width":1200,"height":1200,"caption":"S8700130_0"},{"@type":"BreadcrumbList","@id":"https:\/\/tupique.com\/pt\/product\/voile-dombrage-vela-sombreo-vert-500-x-500-x-05-cm-auvent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"commencer","item":"https:\/\/tupique.com\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/tupique.com\/pt\/loja\/"},{"@type":"ListItem","position":3,"name":"Voile d&#8217;ombrage Vela sombreo Vert 500 x 500 x 0,5 cm Auvent"}]},{"@type":"WebSite","@id":"https:\/\/tupique.com\/#website","url":"https:\/\/tupique.com\/","name":"Tupique","description":"","publisher":{"@id":"https:\/\/tupique.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tupique.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/tupique.com\/#organization","name":"Tupique","url":"https:\/\/tupique.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/tupique.com\/#\/schema\/logo\/image\/","url":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/03\/logo-tupique-1.webp","contentUrl":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/03\/logo-tupique-1.webp","width":500,"height":67,"caption":"Tupique"},"image":{"@id":"https:\/\/tupique.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/product\/187646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/comments?post=187646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/media\/187640"}],"wp:attachment":[{"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/media?parent=187646"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/product_brand?post=187646"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/product_cat?post=187646"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/product_tag?post=187646"},{"taxonomy":"woo-feed-brand","embeddable":true,"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/woo-feed-brand?post=187646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}