{"id":1378,"count":45,"description":"","link":"https:\/\/tupique.com\/pt\/categoria-produto\/parfum-cosmetique\/cosmetiques\/","name":"Cosm\u00e9ticos","slug":"cosmetiques","taxonomy":"product_cat","parent":769,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cosm\u00e9tiques Archives - Tupique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tupique.com\/pt\/categoria-produto\/parfum-cosmetique\/cosmetiques\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cosm\u00e9tiques Archives - Tupique\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tupique.com\/pt\/categoria-produto\/parfum-cosmetique\/cosmetiques\/\" \/>\n<meta property=\"og:site_name\" content=\"Tupique\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/tupique.com\\\/categoria-produto\\\/parfum-cosmetique\\\/cosmetiques\\\/\",\"url\":\"https:\\\/\\\/tupique.com\\\/categoria-produto\\\/parfum-cosmetique\\\/cosmetiques\\\/\",\"name\":\"Cosm\u00e9tiques Archives - Tupique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/categoria-produto\\\/parfum-cosmetique\\\/cosmetiques\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tupique.com\\\/categoria-produto\\\/parfum-cosmetique\\\/cosmetiques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"commencer\",\"item\":\"https:\\\/\\\/tupique.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parfum | Cosm\u00e9tique\",\"item\":\"https:\\\/\\\/tupique.com\\\/categoria-produto\\\/parfum-cosmetique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cosm\u00e9tiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tupique.com\\\/#website\",\"url\":\"https:\\\/\\\/tupique.com\\\/\",\"name\":\"Tupique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tupique.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tupique.com\\\/#organization\",\"name\":\"Tupique\",\"url\":\"https:\\\/\\\/tupique.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/tupique.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-tupique-1.webp\",\"contentUrl\":\"https:\\\/\\\/tupique.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-tupique-1.webp\",\"width\":500,\"height\":67,\"caption\":\"Tupique\"},\"image\":{\"@id\":\"https:\\\/\\\/tupique.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cosm\u00e9tiques Archives - Tupique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tupique.com\/pt\/categoria-produto\/parfum-cosmetique\/cosmetiques\/","og_locale":"pt_PT","og_type":"article","og_title":"Cosm\u00e9tiques Archives - Tupique","og_url":"https:\/\/tupique.com\/pt\/categoria-produto\/parfum-cosmetique\/cosmetiques\/","og_site_name":"Tupique","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/tupique.com\/categoria-produto\/parfum-cosmetique\/cosmetiques\/","url":"https:\/\/tupique.com\/categoria-produto\/parfum-cosmetique\/cosmetiques\/","name":"Cosm\u00e9tiques Archives - Tupique","isPartOf":{"@id":"https:\/\/tupique.com\/#website"},"breadcrumb":{"@id":"https:\/\/tupique.com\/categoria-produto\/parfum-cosmetique\/cosmetiques\/#breadcrumb"},"inLanguage":"pt-PT"},{"@type":"BreadcrumbList","@id":"https:\/\/tupique.com\/categoria-produto\/parfum-cosmetique\/cosmetiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"commencer","item":"https:\/\/tupique.com\/"},{"@type":"ListItem","position":2,"name":"Parfum | Cosm\u00e9tique","item":"https:\/\/tupique.com\/categoria-produto\/parfum-cosmetique\/"},{"@type":"ListItem","position":3,"name":"Cosm\u00e9tiques"}]},{"@type":"WebSite","@id":"https:\/\/tupique.com\/#website","url":"https:\/\/tupique.com\/","name":"Tupique","description":"","publisher":{"@id":"https:\/\/tupique.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tupique.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/tupique.com\/#organization","name":"Tupique","url":"https:\/\/tupique.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/tupique.com\/#\/schema\/logo\/image\/","url":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/03\/logo-tupique-1.webp","contentUrl":"https:\/\/tupique.com\/wp-content\/uploads\/2026\/03\/logo-tupique-1.webp","width":500,"height":67,"caption":"Tupique"},"image":{"@id":"https:\/\/tupique.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/product_cat\/1378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/product_cat\/769"}],"wp:post_type":[{"href":"https:\/\/tupique.com\/pt\/wp-json\/wp\/v2\/product?product_cat=1378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}